{"id":7871,"date":"2019-11-28T17:24:50","date_gmt":"2019-11-28T15:24:50","guid":{"rendered":"https:\/\/jonglezpublishing.com\/?post_type=product&#038;p=7871"},"modified":"2026-05-25T15:20:13","modified_gmt":"2026-05-25T12:20:13","slug":"grand-paris-insolite-et-secret","status":"publish","type":"product","link":"https:\/\/jonglezpublishing.com\/fr\/produit\/grand-paris-insolite-et-secret\/","title":{"rendered":"GRAND PARIS INSOLITE ET SECRET"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb woodmart_inline=\u00a0\u00bbno\u00a0\u00bb text_larger=\u00a0\u00bbno\u00a0\u00bb]Les vestiges oubli\u00e9s du pont des Arts parisien, un globe terrestre de 5 m\u00e8tres de diam\u00e8tre au croisement de deux rues de Suresnes, l\u2019ancien pavillon de Norv\u00e8ge de l\u2019Exposition universelle de 1889 transform\u00e9 en temple protestant, un coron \u00e0 Clamart, une \u00e9cole dans l\u2019ancienne soufflerie des usines a\u00e9ronautiques Hispano-Suiza, une coul\u00e9e verte m\u00e9connue \u00e0 Colombes, un authentique menhir transform\u00e9 en monument comm\u00e9moratif de la Lib\u00e9ration, une splendide mosa\u00efque d\u2019\u00e9poque romaine oubli\u00e9e dans une \u00e9glise, une empreinte de pneu g\u00e9ante dans un parc, des coins de campagne insoup\u00e7onn\u00e9s, une superbe coupole en b\u00e9ton dit \u00abtranslucide\u00bb, le marbre de la table o\u00f9 fut assassin\u00e9 Jean Jaur\u00e8s \u00e0 Champigny-sur-Marne, le plus beau nymph\u00e9e aux coquillages de France&#8230;<\/p>\n<p>M\u00e9connu des Parisiens voire de ses propres habitants, le Grand Paris fut au cours de son histoire mouvement\u00e9e un lieu d\u2019exp\u00e9rimentations en tous genres que ne permettait pas la n\u00e9cessaire majest\u00e9 de la capitale. Il poss\u00e8de en cons\u00e9quence un patrimoine d\u2019une richesse insoup\u00e7onn\u00e9e qui est un terrain de jeu fantastique pour les curieux qui sont pr\u00eats \u00e0 passer le p\u00e9riph\u00e9rique ou \u00e0 aller voir ce qui se passe dans la ville d\u2019\u00e0 c\u00f4t\u00e9.<\/p>\n<p>Un guide indispensable pour ceux qui pensaient bien conna\u00eetre le Grand Paris ou pour ceux qui souhaitent d\u00e9couvrir son autre visage.<\/p>\n<p><b>AUTEUR <\/b>: Michael Mendes<br \/>\n<b>PAGES <\/b>: 360<br \/>\n<b>FORMAT <\/b>: 10.5 x 19 cm<br \/>\n<b>ISBN <\/b>: 978-2-36195-957-9<br \/>\n<b>PRIX <\/b>: 18,95 \u20ac<br \/>\n<b>CONTACT <\/b>: <a href=\"mailto:info@editionsjonglez.com\">info@editionsjonglez.com<\/a><\/p>\n<div class=\"buttons_cont\">\n<div class=\"button_cont\" align=\"center\"><a class=\"gv_product_btn\" href=\"https:\/\/jonglezpublishing.com\/wp-content\/uploads\/2019\/11\/Couv_Grand-Paris_RVB-scaled.jpg\" target=\"_blank\" rel=\"noopener\">T\u00e9l\u00e9charger la couverture<\/a><\/div>\n<div class=\"button_cont\" align=\"center\"><a class=\"gv_product_btn\" href=\"https:\/\/jonglezpublishing.com\/wp-content\/uploads\/2026\/05\/Extrait-PDF-Grand-Paris.pdf\" target=\"_blank\" rel=\"noopener\">Consulter le PDF<\/a><\/div>\n<div class=\"button_cont\" align=\"center\"><a class=\"gv_product_btn\" href=\"https:\/\/livre.fnac.com\/a13517109\/Michael-Mendes-Grand-Paris-insolite-et-secret#omnsearchpos=1\" target=\"_blank\" rel=\"noopener noreferrer\">Acheter en ligne<\/a><\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb woodmart_inline=\u00a0\u00bbno\u00a0\u00bb text_larger=\u00a0\u00bbno\u00a0\u00bb]Les vestiges oubli\u00e9s du pont des Arts parisien, un globe terrestre de 5 m\u00e8tres de diam\u00e8tre au<\/p>\n","protected":false},"featured_media":15664,"template":"","meta":[],"product_brand":[],"product_cat":[283,292,420],"product_tag":[],"class_list":{"0":"post-7871","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-french-2","7":"product_cat-french-fr","8":"product_cat-guides-insolites","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/jonglezpublishing.com\/fr\/wp-json\/wp\/v2\/product\/7871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonglezpublishing.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jonglezpublishing.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonglezpublishing.com\/fr\/wp-json\/wp\/v2\/media\/15664"}],"wp:attachment":[{"href":"https:\/\/jonglezpublishing.com\/fr\/wp-json\/wp\/v2\/media?parent=7871"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jonglezpublishing.com\/fr\/wp-json\/wp\/v2\/product_brand?post=7871"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jonglezpublishing.com\/fr\/wp-json\/wp\/v2\/product_cat?post=7871"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jonglezpublishing.com\/fr\/wp-json\/wp\/v2\/product_tag?post=7871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}